{"id":377,"date":"2025-07-25T10:24:52","date_gmt":"2025-07-25T10:24:52","guid":{"rendered":"https:\/\/imjoexperiences.com\/?page_id=377"},"modified":"2025-12-09T11:01:29","modified_gmt":"2025-12-09T11:01:29","slug":"bienestar","status":"publish","type":"page","link":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/","title":{"rendered":"Bienestar"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section preset--group--divi-section--divi-sizing--default preset--module--divi-section--default\">\n<div class=\"et_pb_row_0 et_pb_row et_pb_gutters1 et_block_row preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><p>BIENESTAR<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module textAnimation preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><h1>Eco-lujo en Barcelona<\/h1>\n<\/div><\/div>\n\n\n\n\n\n\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_animated et_pb_module et_block_module light\" href=\"https:\/\/imjoexperiences.com\/es\/contacto\/\" data-icon=\"5\">CONT\u00c1CTANOS<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><p>M\u00c1S EXPERIENCIA<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_flex_row preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_2 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"dsm_persepective_image_0 dsm_persepective_image et_pb_module\"><div class=\"et_pb_module_inner\"><div class=\"dsm-perspective-image-wrapper et_pb_has_overlay  \">\n\t\t\t\t\t<span class=\"et_pb_image_wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/imjoexperiences.com\/wp-content\/uploads\/2025\/07\/sostenible_masexperiencias_2.jpg\" \/>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t \n\t\t\t <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><p><strong>Te invitamos a viajar desde una perspectiva tranquila, exclusiva y sostenible<\/strong><\/p>\n<p>Este viaje combina lo mejor del eco-lujo con experiencias culturales, bienestar y gastronom\u00eda local.<\/p>\n<p>Desde tu llegada hasta tu partida vivir\u00e1s cada momento a un ritmo m\u00e1s consciente y aut\u00e9ntico.<\/p>\n<p>Un viaje donde la sostenibilidad y la elegancia conviven en perfecta armon\u00eda.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section preset--group--divi-section--divi-sizing--default preset--module--divi-section--default\">\n<div class=\"et_pb_row_3 et_pb_row et_flex_row et_animated preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_4 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><p>AS\u00cd ES VIAJAR CON NOSOTROS<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_flex_row preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_5 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module preset--group--divi-blurb--divi-sizing--default preset--group--divi-blurb--divi-font-body--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/imjoexperiences.com\/wp-content\/uploads\/2025\/07\/experiencias_personalizadas.svg\" class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone wp-image-308\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Experiencias personalizadas<\/h4><div class=\"et_pb_blurb_description\"><p>No seguimos rutas, las creamos contigo<\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_6 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module preset--group--divi-blurb--divi-sizing--default preset--group--divi-blurb--divi-font-body--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/imjoexperiences.com\/wp-content\/uploads\/2025\/07\/concierge_tiempo_real.svg\" class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone wp-image-306\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Concierge a tiempo real<\/h4><div class=\"et_pb_blurb_description\"><p>Te acompa\u00f1amos antes, durante y despu\u00e9s del viaje para que solo te ocupes de disfrutar<\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module preset--group--divi-blurb--divi-sizing--default preset--group--divi-blurb--divi-font-body--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/imjoexperiences.com\/wp-content\/uploads\/2025\/07\/conexiones-locales.svg\" class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone wp-image-307\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Conexiones locales aut\u00e9nticas<\/h4><div class=\"et_pb_blurb_description\"><p>Conecta con lo aut\u00e9ntico, lo \u00edntimo, lo memorable<\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section preset--group--divi-section--divi-sizing--default preset--module--divi-section--default\">\n<div class=\"et_pb_row_5 et_pb_row et_flex_row fila_sangre preset--group--divi-row--divi-sizing--default preset--module--divi-row--default\">\n<div class=\"et_pb_column_8 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_3_5 et_flex_column_24_24_phone sangre_izquierda preset--group--divi-column--divi-sizing--default\">\n<div class=\"dsm_persepective_image_1 dsm_persepective_image et_pb_module nm\"><div class=\"et_pb_module_inner\"><div class=\"dsm-perspective-image-wrapper et_pb_has_overlay  dsm-force-fullwidth\">\n\t\t\t\t\t<span class=\"et_pb_image_wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/imjoexperiences.com\/wp-content\/uploads\/2025\/07\/sostenible_viajeamida_2-1.jpg\" \/>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t \n\t\t\t <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_2_5 et_flex_column_24_24_phone preset--group--divi-column--divi-sizing--default\">\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module textAnimation preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><h2 style=\"text-align: center;\">\u00bfPrefieres tu viaje a medida?<\/h2>\n<\/div><\/div>\n\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--group--divi-text--divi-sizing--default preset--group--divi-text--divi-font-body--default\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\">Dise\u00f1amos viajes exclusivos y experiencias de lujo personalizadas, adaptadas a tus gustos, ritmo y necesidades.<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_animated et_pb_module et_block_module\" href=\"https:\/\/imjoexperiences.com\/es\/contacto\/\" data-icon=\"5\">CONT\u00c1CTANOS<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":246,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-377","page","type-page","status-publish","hentry"],"acf":[],"dsm_author":{"name":"cactussenygrafic","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bb454ee17ba8e47272d849674b566136b7ec16cd0105cc978af9d0592d1fb69a?s=96&d=mm&r=g","archive_link":"https:\/\/imjoexperiences.com\/es\/author\/cactussenygrafic\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Experiencia Wellness de lujo en Barcelona | IM&amp;JO<\/title>\n<meta name=\"description\" content=\"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiencia Wellness de lujo en Barcelona | IM&amp;JO\" \/>\n<meta property=\"og:description\" content=\"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/\" \/>\n<meta property=\"og:site_name\" content=\"IM&amp;JO\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T11:01:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/\",\"url\":\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/\",\"name\":\"Experiencia Wellness de lujo en Barcelona | IM&JO\",\"isPartOf\":{\"@id\":\"https:\/\/imjoexperiences.com\/es\/#website\"},\"datePublished\":\"2025-07-25T10:24:52+00:00\",\"dateModified\":\"2025-12-09T11:01:29+00:00\",\"description\":\"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.\",\"breadcrumb\":{\"@id\":\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/imjoexperiences.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiencias\",\"item\":\"https:\/\/imjoexperiences.com\/es\/experiencias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bienestar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/imjoexperiences.com\/es\/#website\",\"url\":\"https:\/\/imjoexperiences.com\/es\/\",\"name\":\"IM&amp;JO\",\"description\":\"Viajes a medida, adaptados a ti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/imjoexperiences.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiencia Wellness de lujo en Barcelona | IM&JO","description":"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/","og_locale":"es_ES","og_type":"article","og_title":"Experiencia Wellness de lujo en Barcelona | IM&JO","og_description":"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.","og_url":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/","og_site_name":"IM&amp;JO","article_modified_time":"2025-12-09T11:01:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/","url":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/","name":"Experiencia Wellness de lujo en Barcelona | IM&JO","isPartOf":{"@id":"https:\/\/imjoexperiences.com\/es\/#website"},"datePublished":"2025-07-25T10:24:52+00:00","dateModified":"2025-12-09T11:01:29+00:00","description":"La escapada reparadora que necesitas. Una experiencia de bienestar exquisita que combina cultura y relax en los mejores eco resort de lujo de Barcelona.","breadcrumb":{"@id":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/imjoexperiences.com\/es\/experiencias\/bienestar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imjoexperiences.com\/es\/"},{"@type":"ListItem","position":2,"name":"Experiencias","item":"https:\/\/imjoexperiences.com\/es\/experiencias\/"},{"@type":"ListItem","position":3,"name":"Bienestar"}]},{"@type":"WebSite","@id":"https:\/\/imjoexperiences.com\/es\/#website","url":"https:\/\/imjoexperiences.com\/es\/","name":"IM&amp;JO","description":"Viajes a medida, adaptados a ti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imjoexperiences.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/pages\/377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/comments?post=377"}],"version-history":[{"count":29,"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/pages\/377\/revisions"}],"predecessor-version":[{"id":2505,"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/pages\/377\/revisions\/2505"}],"up":[{"embeddable":true,"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/pages\/246"}],"wp:attachment":[{"href":"https:\/\/imjoexperiences.com\/es\/wp-json\/wp\/v2\/media?parent=377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}